{"id":947,"date":"2014-09-25T17:00:59","date_gmt":"2014-09-25T20:00:59","guid":{"rendered":"http:\/\/www.carlosmontes.cl\/senador\/?p=947"},"modified":"2014-09-29T13:45:07","modified_gmt":"2014-09-29T16:45:07","slug":"estado-subsidiario-restringe-el-desarrollo-de-una-sociedad-moderna","status":"publish","type":"post","link":"https:\/\/www.carlosmontes.cl\/senador\/estado-subsidiario-restringe-el-desarrollo-de-una-sociedad-moderna\/","title":{"rendered":"Estado subsidiario restringe el desarrollo de una sociedad moderna"},"content":{"rendered":"<p style=\"text-align: justify;\">El Senador Montes particip\u00f3 en el\u00a0<em>Seminario Internacional de Alta Direcci\u00f3n P\u00fablica 2014: Nuevos Desaf\u00edos y Reformas Pendientes<\/em>, organizado por el <a href=\"http:\/\/www.serviciocivil.gob.cl\/\" target=\"_blank\">Servicio Civil<\/a>, el Consejo de Alta Direcci\u00f3n P\u00fablica y el Senado. En su presentaci\u00f3n, Montes <strong>destac\u00f3 lo avanzado que est\u00e1 a nivel continental el sistema de Alta Direcci\u00f3n P\u00fablica, as\u00ed como la necesidad de seguir su perfeccionamiento<\/strong>. \u201cNo podemos eludir la discusi\u00f3n sobre qu\u00e9 tipo de Estado queremos. La profesionalizaci\u00f3n de los funcionarios p\u00fablicos tiene que ver eso\u201d, enfatiz\u00f3.<\/p>\n<p style=\"text-align: justify;\">En tal sentido, se\u00f1al\u00f3 que la Nueva Mayor\u00eda considera que \u201c<strong>el modelo de estado subsidiario, como se define en la Constituci\u00f3n, limita, restringe, las posibilidades de desarrollo de una sociedad moderna como la nuestra<\/strong>\u201d.<\/p>\n<p style=\"text-align: justify;\">Se refiri\u00f3 a que <strong>est\u00e1 superada la noci\u00f3n de un estado que se haga cargo de todo<\/strong>. \u201cEn nuestros tiempos, el Estado tiene que ser capaz de articular su propio esfuerzo, con el de la sociedad civil y con la del mercado. Un estado din\u00e1mico que se haga cargo de las necesidades de sus habitantes\u201d.<\/p>\n<p style=\"text-align: justify;\">Respecto del <strong>Sistema de Alta Direcci\u00f3n P\u00fablica<\/strong> plante\u00f3 la <strong>necesidad de que retome el objetivo de seguimiento y evaluaci\u00f3n de los funcionarios<\/strong>. As\u00ed mismo, habl\u00f3 de <strong>crear tres niveles de cargos, los que siempre deben ser seleccionados por sus capacidades t\u00e9cnicas<\/strong>. \u201cTenemos que asumir que hay un primer nivel que depende de la sensibilidad pol\u00edtica del gobierno de turno\u201d, explic\u00f3. \u201cLuego, podr\u00eda existir nivel que combine la sensibilidad pol\u00edtica con lo t\u00e9cnico y, finalmente, un tercer nivel s\u00f3lo t\u00e9cnico, independiente de la corriente pol\u00edtica del funcionario, que la autoridad no pueda destituir, y que sea el encargado de otorgar capacidad, solidez y estabilidad al funcionamiento del Estado\u201d, termin\u00f3.<\/p>\n<p style=\"text-align: justify;\">En el panel en el que tambi\u00e9n expusieron los senadores Ignacio Walker (DC) y Jos\u00e9 Garc\u00eda (RN) y el diputado Ernesto Silva (UDI).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Senador Montes particip\u00f3 en el Seminario Internacional de Alta Direcci\u00f3n P\u00fablica 2014: \u00abNuevos Desaf\u00edos y Reformas Pendientes\u00bb, organizado por el Servicio Civil, el Consejo de Alta Direcci\u00f3n P\u00fablica y el Senado. Destac\u00f3 lo avanzado del sistema de Alta Direcci\u00f3n P\u00fablica, as\u00ed como la necesidad de continuar su perfeccionamiento. <\/p>\n","protected":false},"author":3,"featured_media":949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[455,274,456,457],"_links":{"self":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/947"}],"collection":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":4,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"predecessor-version":[{"id":952,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/947\/revisions\/952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media\/949"}],"wp:attachment":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}