{"id":343,"date":"2014-05-02T16:36:58","date_gmt":"2014-05-02T20:36:58","guid":{"rendered":"http:\/\/www.carlosmontes.cl\/senador\/?p=343"},"modified":"2014-05-02T16:36:58","modified_gmt":"2014-05-02T20:36:58","slug":"senador-montes-participo-en-acto-de-la-cut-por-el-1-de-mayo","status":"publish","type":"post","link":"https:\/\/www.carlosmontes.cl\/senador\/senador-montes-participo-en-acto-de-la-cut-por-el-1-de-mayo\/","title":{"rendered":"Senador Montes particip\u00f3 en acto de la CUT por el 1\u00b0 de Mayo"},"content":{"rendered":"<p>Como ha sido frecuente en los \u00faltimos a\u00f1os, el senador Carlos Montes particip\u00f3 del acto con que la Central Unitaria de Trabajadores, CUT, conmemor\u00f3 el D\u00eda del Trabajador. El legislador valor\u00f3 el mensaje de la Presidenta de la multisindical, B\u00e1rbara Figueroa, en apoyo a la reforma tributaria y demandando modificaciones profundas al C\u00f3digo del Trabajo.<\/p>\n<p>Montes recalc\u00f3 la necesidad de impulsar a la brevedad reformas legales que permitan promover y apoyar la sindicalizaci\u00f3n, ampliar y extender la negociaci\u00f3n colectiva y fortalecer el derecho a la huelga. \u00abNecesitamos mejorar la equidad en las relaciones laborales, con el objeto de mejorar la distribuci\u00f3n de los ingresos a nivel de empresa y terminar con pr\u00e1cticas abusivas como el multirut\u00bb &#8211; sentenci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como ha sido frecuente en los \u00faltimos a\u00f1os, el senador Carlos Montes particip\u00f3 del acto con que la Central Unitaria de Trabajadores, CUT, conmemor\u00f3 el D\u00eda del Trabajador. El legislador valor\u00f3 el mensaje de la Presidenta de la multisindical, B\u00e1rbara Figueroa, en apoyo a la reforma tributaria y demandando modificaciones profundas al C\u00f3digo del Trabajo. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,2],"tags":[125,124,134,132,126,131,129,130,127,133,128,123,122],"_links":{"self":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/343"}],"collection":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":1,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"predecessor-version":[{"id":345,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/343\/revisions\/345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media\/344"}],"wp:attachment":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/tags?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}