{"id":1954,"date":"2016-07-06T18:10:33","date_gmt":"2016-07-06T22:10:33","guid":{"rendered":"http:\/\/www.carlosmontes.cl\/senador\/?p=1954"},"modified":"2023-03-13T10:00:23","modified_gmt":"2023-03-13T13:00:23","slug":"parlamentarios-piden-fortalecer-universidades-estatales","status":"publish","type":"post","link":"https:\/\/www.carlosmontes.cl\/senador\/parlamentarios-piden-fortalecer-universidades-estatales\/","title":{"rendered":"Parlamentarios piden fortalecer universidades estatales"},"content":{"rendered":"<p style=\"text-align: justify;\">Un amplio grupo de senadores y diputados de diversas bancadas e independientes suscribieron una <a title=\"Declaraci\u00f3n P\u00fablica Universidades Estatales\" href=\"http:\/\/www.carlosmontes.cl\/senador\/wp-content\/uploads\/2016\/07\/DECLARACI\u00d3N-P\u00daBLICA-educ.superiorfirmas.pdf\" target=\"_blank\" rel=\"noopener\">declaraci\u00f3n p\u00fablica<\/a> en la que se\u00f1alan su convicci\u00f3n en torno a la necesidad de que el proyecto de ley sobre educaci\u00f3n superior, ingresado recientemente a tramitaci\u00f3n legislativa, considere especialmente el rol de las universidades estatales.<\/p>\n<p style=\"text-align: justify;\">En el texto, los legisladores afirman que \u00ab\u00bbcorresponde a las instituciones del Estado, tanto universidades como Centros de Formaci\u00f3n T\u00e9cnica (Institutos Tecnol\u00f3gicos) estructurar el sistema, garantizando el derecho social a la educaci\u00f3n, velando por la promoci\u00f3n de la democracia y los derechos humanos, asegurando la integraci\u00f3n social y empujando el desarrollo econ\u00f3mico y espiritual de la naci\u00f3n.\u00bb Advierten, en todo caso, que lo anterior\u00a0no obsta a \u00abreconocer y valorar el aporte de instituciones no estatales que, hist\u00f3ricamente, desde sus proyectos espec\u00edficos, han contribuido a estos objetivos de bien p\u00fablico con responsabilidad y compromiso.\u00bb<\/p>\n<p style=\"text-align: justify;\">A juicio de los parlamentarios, esta especial consideraci\u00f3n de los planteles estatales amerita \u00abiniciar un proceso decidido tendiente a fortalecer las instituciones de educaci\u00f3n superior del Estado, a trav\u00e9s de un financiamiento tanto para la gratuidad como basal permanente y de un plan de inversiones en infraestructura y recursos humanos que aseguren su crecimiento cuantitativo y cualitativo.\u00bb<\/p>\n<p style=\"text-align: justify;\">Apuntan, adem\u00e1s, a que la incorporaci\u00f3n de recursos\u00a0para avanzar hacia\u00a0la gratuidad del sistema \u00abdebe ir acompa\u00f1ada de los procedimientos de control y sanci\u00f3n adecuados para garantizar la ausencia de lucro y el buen uso de los recursos p\u00fablicos comprometidos. Los aportes que efect\u00faa el Fisco, de manera directa o indirecta, a Universidades, Institutos Profesionales y Centros de Formaci\u00f3n T\u00e9cnica, deben administrarse con absoluta transparencia.\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Cobertura de Prensa:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"T13\" href=\"http:\/\/www.t13.cl\/noticia\/politica\/parlamentarios-nueva-mayoria-presionan-mayor-reconocimiento-universidades-estatales\" target=\"_blank\" rel=\"noopener\">Teletrece Radio<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.adnradio.cl\/noticias\/nacional\/parlamentarios-de-la-nueva-mayoria-respaldan-a-rectores-de-universidades-estatales\/20160705\/nota\/3180732.aspx\" target=\"_blank\" rel=\"noopener\">ADN Radio<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.economiaynegocios.cl\/noticias\/noticias.asp?id=268683\" target=\"_blank\" rel=\"noopener\">El Mercurio<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.uchile.cl\/noticias\/123279\/universidades-estatales-reciben-apoyo-parlamentario-ante-reforma\" target=\"_blank\" rel=\"noopener\">Universidad de Chile<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un amplio grupo de senadores y diputados de diversas bancadas e independientes suscribieron una declaraci\u00f3n p\u00fablica en la que se\u00f1alan su convicci\u00f3n en torno a la necesidad de que el proyecto de ley sobre educaci\u00f3n superior, ingresado recientemente a tramitaci\u00f3n legislativa, considere especialmente el rol de las universidades estatales. En el texto, los legisladores afirman &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1955,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,2],"tags":[72,248,934,741,70,18,196,706,658,705,214,71,423,679,79,935],"_links":{"self":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/1954"}],"collection":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/comments?post=1954"}],"version-history":[{"count":3,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/1954\/revisions"}],"predecessor-version":[{"id":2337,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/posts\/1954\/revisions\/2337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media\/1955"}],"wp:attachment":[{"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/media?parent=1954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/categories?post=1954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carlosmontes.cl\/senador\/wp-json\/wp\/v2\/tags?post=1954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}